{"id":1,"date":"2025-07-30T17:24:45","date_gmt":"2025-07-30T17:24:45","guid":{"rendered":"https:\/\/coopsoli.baita.app.br\/?p=1"},"modified":"2025-12-16T09:54:05","modified_gmt":"2025-12-16T12:54:05","slug":"2o-dia-de-campo-de-citros-em-alto-parana-coopsoli","status":"publish","type":"post","link":"https:\/\/coopsoli.com.br\/en\/2o-dia-de-campo-de-citros-em-alto-parana-coopsoli\/","title":{"rendered":"2\u00ba Dia de Campo de Citros re\u00fane produtores e t\u00e9cnicos em Alto Paran\u00e1"},"content":{"rendered":"<h4 style=\"text-align: left;\" data-rm-block-id=\"block-1\"><span class=\"fontSizeLarge\">Promovido na tarde sexta-feira (16\/5) pela Cocamar Cooperativa Agroindustrial e a Cooperativa de Produtores do Mercado Solid\u00e1rio (Coopsoli) em Alto Paran\u00e1, na regi\u00e3o noroeste do estado, o 2\u00ba Dia de Campo de Citros contou com a participa\u00e7\u00e3o de produtores e t\u00e9cnicos das unidades da cooperativa localizadas nos vizinhos munic\u00edpios de Nova Esperan\u00e7a e Paranava\u00ed. O evento aconteceu na Fazenda Kanabushi, do cooperado Yoshichiro Kanabushi.<\/span><br \/>\n<span class=\"fontSizeLarge\">\u00a0<\/span><br \/>\n<span class=\"fontSizeLarge\">Em pauta, abordagens sobre tratos culturais e controle de doen\u00e7as. Ao final, o especialista e consultor, engenheiro agr\u00f4nomo Luis Scandelai, palestrou sobre o manejo das principais enfermidades, com foco principalmente no greening. \u00a0<\/span><br \/>\n<span class=\"fontSizeLarge\">\u00a0<\/span><br \/>\n<span class=\"fontSizeLarge\">\u201cFoi uma tarde enriquecedora, repleta de oportunidades para novos aprendizados e troca de conhecimentos\u201d, destacou o gerente de Culturas Perenes da Cocamar, Gabriel Costa. Segundo ele, iniciativas como essa fortalecem ainda mais o v\u00ednculo com os cooperados, ressaltando ainda o compromisso da Cocamar com o desenvolvimento da citricultura na regi\u00e3o. \u201cO Dia de Campo refor\u00e7a a import\u00e2ncia da difus\u00e3o de informa\u00e7\u00f5es t\u00e9cnicas qualificadas e da ado\u00e7\u00e3o de pr\u00e1ticas que promovam maior efici\u00eancia produtiva e sustentabilidade ao setor\u201d, completou.<\/span><\/h4>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-1 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/coopsoli.com.br\/en\/2o-dia-de-campo-de-citros-em-alto-parana-coopsoli\/noticia-1-foto-3\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-3.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-3.webp 960w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-3-225x300.webp 225w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-3-768x1024.webp 768w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-3-9x12.webp 9w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h4 style=\"text-align: left;\"><span class=\"fontSizeLarge\">Al\u00e9m da quest\u00e3o sanit\u00e1ria, um dos temas apresentados foi a import\u00e2ncia da aduba\u00e7\u00e3o de pr\u00e9-florada na cultura, discutindo-se como essa pr\u00e1tica nutricional desempenha um papel fundamental no desenvolvimento das plantas, assegurando uma adequada nutri\u00e7\u00e3o antes da flora\u00e7\u00e3o. Foram destacadas as influ\u00eancias diretas da aduba\u00e7\u00e3o no potencial produtivo do pomar, incluindo a qualidade da flora\u00e7\u00e3o, o pegamento dos frutos e o equil\u00edbrio nutricional, fatores essenciais para uma colheita mais eficiente e rent\u00e1vel.<\/span><\/h4>\n<h4>O evento contou com o apoio das empresas Yara, Nortox e Bayer, al\u00e9m de Fertilizantes Viridian e Cocamar M\u00e1quinas\/Concession\u00e1ria John Deere.<\/h4>\n<div id='gallery-2' class='gallery galleryid-1 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/coopsoli.com.br\/en\/2o-dia-de-campo-de-citros-em-alto-parana-coopsoli\/noticia-1-foto-2\/'><img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-2.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-2.webp 960w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-2-300x225.webp 300w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-2-768x576.webp 768w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/07\/noticia-1-foto-2-16x12.webp 16w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Promovido na tarde sexta-feira (16\/5) pela Cocamar Cooperativa Agroindustrial e a Cooperativa de Produtores do Mercado Solid\u00e1rio (Coopsoli) em Alto Paran\u00e1, na regi\u00e3o noroeste do estado, o 2\u00ba Dia de Campo de Citros contou com a participa\u00e7\u00e3o de produtores e t\u00e9cnicos das unidades da cooperativa localizadas nos vizinhos munic\u00edpios de Nova Esperan\u00e7a e Paranava\u00ed. O [&hellip;]<\/p>","protected":false},"author":1,"featured_media":841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24,1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-excelencia-na-citricultura","category-novidades"],"acf":[],"_links":{"self":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":13,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":854,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts\/1\/revisions\/854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/media\/841"}],"wp:attachment":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}