{"id":108,"date":"2025-08-01T19:45:44","date_gmt":"2025-08-01T22:45:44","guid":{"rendered":"https:\/\/coopsoli.baita.app.br\/?p=108"},"modified":"2025-12-16T13:42:52","modified_gmt":"2025-12-16T16:42:52","slug":"post-teste-2","status":"publish","type":"post","link":"https:\/\/coopsoli.com.br\/en\/post-teste-2\/","title":{"rendered":"Conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o em Atalaia (PR) sobre o avan\u00e7o do greening na Laranja"},"content":{"rendered":"<h5 class=\"noSpacingAbove noSpacingBelow\" data-text-type=\"noSpacing\" data-rm-block-id=\"block-1\"><span class=\"fontSizeXLarge\">Nos dias 24 e 25 de julho, durante o Festival de Rodeio em Atalaia, munic\u00edpio da regi\u00e3o noroeste do Paran\u00e1, a equipe t\u00e9cnica da Cocamar Cooperativa Agroindustrial e da Cooperativa de Produtores do Mercado Solid\u00e1rio (Coopsoli) promoveu uma a\u00e7\u00e3o de conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o em geral sobre o greening, doen\u00e7a que ainda n\u00e3o tem tratamento e afeta os pomares de laranja.<\/span><\/h5>\n<h5 data-rm-block-id=\"block-3\"><span class=\"fontSizeXLarge\">A iniciativa alcan\u00e7ou mais de 2 mil pessoas, que foram informadas sobre a gravidade da doen\u00e7a, seus sintomas e as medidas de preven\u00e7\u00e3o que a comunidade deve adotar, como a erradica\u00e7\u00e3o de plantas de citros em quintais e pequenas ch\u00e1caras, por serem hospedeiras do psil\u00eddeo, o inseto transmissor da bact\u00e9ria causadora da enfermidade.<\/span><\/h5>\n<h5 data-rm-block-id=\"block-5\"><span class=\"fontSizeXLarge\">A citricultura \u00e9 uma importante atividade econ\u00f4mica do noroeste paranaense, envolvendo centenas de produtores e gerando milhares de postos de trabalho, al\u00e9m de movimentar o com\u00e9rcio das cidades. O evento em Atalaia est\u00e1 em linha com a\u00e7\u00f5es organizadas em escolas, feiras do produtor e exposi\u00e7\u00f5es agropecu\u00e1rias em Nova Esperan\u00e7a e Paranava\u00ed, entre outras.<\/span><\/h5>\n<h5 data-rm-block-id=\"block-7\"><span class=\"fontSizeXLarge\">\u201cPor meio da conscientiza\u00e7\u00e3o, \u00e9 poss\u00edvel proteger n\u00e3o apenas as planta\u00e7\u00f5es, mas tamb\u00e9m o sustento e a qualidade de vida das comunidades que dependem da citricultura, garantindo que este patrim\u00f4nio continue florescendo para as futuras gera\u00e7\u00f5es\u201d, afirma Kelyn Henkemaier, engenheira agr\u00f4noma da Coopsoli.<\/span><\/h5>\n<h4 data-rm-block-id=\"block-9\"><span class=\"fontSizeXLarge\">Na oportunidade, foi feita a divulga\u00e7\u00e3o, tamb\u00e9m, do Ano das Cooperativas, institu\u00eddo pela O<\/span><\/h4>\n<h4 data-rm-block-id=\"block-9\"><span class=\"fontSizeXLarge\">rganiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU), refor\u00e7ando o compromisso que ambas as cooperativ<\/span><\/h4>\n<h4 data-rm-block-id=\"block-9\"><span class=\"fontSizeXLarge\">as t\u00eam com o desenvolvimento do setor agr\u00edcola.<\/span><\/h4>\n<div id='gallery-1' class='gallery galleryid-108 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/coopsoli.com.br\/en\/post-teste-2\/noticia-2-foto-4\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"459\" height=\"602\" src=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-4.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-4.webp 459w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-4-229x300.webp 229w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-4-9x12.webp 9w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/coopsoli.com.br\/en\/post-teste-2\/noticia-2-foto-2\/'><img decoding=\"async\" width=\"400\" height=\"460\" src=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-2.webp 400w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-2-261x300.webp 261w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto-2-10x12.webp 10w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/coopsoli.com.br\/en\/post-teste-2\/noticia-2-foto1\/'><img decoding=\"async\" width=\"393\" height=\"293\" src=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto1.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto1.webp 393w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto1-300x224.webp 300w, https:\/\/coopsoli.com.br\/wp-content\/uploads\/2025\/08\/noticia-2-foto1-16x12.webp 16w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nos dias 24 e 25 de julho, durante o Festival de Rodeio em Atalaia, munic\u00edpio da regi\u00e3o noroeste do Paran\u00e1, a equipe t\u00e9cnica da Cocamar Cooperativa Agroindustrial e da Cooperativa de Produtores do Mercado Solid\u00e1rio (Coopsoli) promoveu uma a\u00e7\u00e3o de conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o em geral sobre o greening, doen\u00e7a que ainda n\u00e3o tem tratamento e [&hellip;]<\/p>","protected":false},"author":1,"featured_media":858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,23],"tags":[],"class_list":["post-108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novidades","category-sustentabilidade-e-impacto-social"],"acf":[],"_links":{"self":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/comments?post=108"}],"version-history":[{"count":8,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts\/108\/revisions"}],"predecessor-version":[{"id":901,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/posts\/108\/revisions\/901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/media\/858"}],"wp:attachment":[{"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/media?parent=108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/categories?post=108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coopsoli.com.br\/en\/wp-json\/wp\/v2\/tags?post=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}